{"id":24699,"date":"2025-01-21T15:59:07","date_gmt":"2025-01-21T14:59:07","guid":{"rendered":"https:\/\/staging.redl.net\/produkt\/pourmybev\/"},"modified":"2026-04-23T15:50:50","modified_gmt":"2026-04-23T13:50:50","slug":"pourmybev","status":"publish","type":"produkt","link":"https:\/\/redl.net\/en\/produkt\/pourmybev\/","title":{"rendered":"PourMyBev"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"24699\" class=\"elementor elementor-24699 elementor-13140\" data-elementor-post-type=\"produkt\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8caafd e-con-full e-flex e-con e-parent\" data-id=\"a8caafd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-32ea454 elementor-hidden-mobile elementor-hidden-tablet e-flex e-con-boxed e-con e-child\" data-id=\"32ea454\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6de4184 elementor-hidden-mobile animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6de4184\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:104,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"726\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-1024x929.jpg\" class=\"attachment-large size-large wp-image-18665\" alt=\"PourMyBev Silexa Pour My Beverage\" srcset=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-1024x929.jpg 1024w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-300x272.jpg 300w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-768x697.jpg 768w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg 1486w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d401db e-con-full e-flex e-con e-child\" data-id=\"5d401db\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b891a83 elementor-hidden-desktop animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"b891a83\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"726\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-1024x929.jpg\" class=\"attachment-large size-large wp-image-18665\" alt=\"PourMyBev Silexa Pour My Beverage\" srcset=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-1024x929.jpg 1024w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-300x272.jpg 300w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-768x697.jpg 768w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg 1486w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a0c1d4 e-flex e-con-boxed e-con e-child\" data-id=\"5a0c1d4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cffff43 e-flex e-con-boxed e-con e-child\" data-id=\"cffff43\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-507bc8e e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"507bc8e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInDown&quot;,&quot;animation_delay&quot;:&quot;800&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a19b5a elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"9a19b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Layer_2\" data-name=\"Layer 2\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 240.72 77.66\">\n  <defs>\n    <style>\n      .cls-1 {\n        fill: \"currentColor\";\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"design\">\n    <g>\n      <polygon class=\"cls-1\" points=\"224.87 1.79 220.28 9.74 229.46 9.74 224.87 1.79\"\/>\n      <polygon class=\"cls-1\" points=\"240.72 9.74 236.13 1.79 231.54 9.74 240.72 9.74\"\/>\n      <polygon class=\"cls-1\" points=\"225.91 19.49 235.09 19.49 230.5 11.54 225.91 19.49\"\/>\n      <polygon class=\"cls-1\" points=\"231.54 10.94 236.13 18.89 240.72 10.94 231.54 10.94\"\/>\n      <polygon class=\"cls-1\" points=\"220.28 10.94 224.87 18.89 229.46 10.94 220.28 10.94\"\/>\n      <polygon class=\"cls-1\" points=\"235.09 1.19 225.91 1.19 230.5 9.14 235.09 1.19\"\/>\n      <polygon class=\"cls-1\" points=\"159.63 23.65 175.21 1.18 162.28 1.18 152.75 15.68 143.22 1.18 140.47 1.18 130.29 1.18 94.57 1.18 94.57 10.68 105.6 10.68 108.11 10.68 136.87 10.68 145.86 23.65 135.14 39.02 105.6 39.02 105.6 29.8 124.72 29.8 124.72 20.34 108.11 20.34 105.6 20.34 94.57 20.34 94.57 48.47 128.55 48.47 138.7 48.47 141.55 48.47 152.75 31.51 162.54 46.3 168.38 36.19 159.63 23.65\"\/>\n      <polygon class=\"cls-1\" points=\"72.8 1.18 61.78 1.18 61.78 48.47 91.97 48.47 91.97 39.02 72.8 39.02 72.8 1.18\"\/>\n      <rect class=\"cls-1\" x=\"44.36\" y=\"1.18\" width=\"11.03\" height=\"47.29\"\/>\n      <path class=\"cls-1\" d=\"M22.88,19.72c-5.74-1.01-10.12-2.3-10.12-5.57,0-2.36,1.49-4.62,7.44-4.62,5.35,0,7.27,2.61,7.27,5.42h11.05c0-9.11-6.22-14.95-17.31-14.95C7.72,0,1.74,5.77,1.74,15.27s10.32,11.3,15.64,12.65c7.2,2.02,11.58,2.51,11.58,7.06,0,3.2-2.43,5.18-8.8,5.18-5.8,0-9.18-2.53-9.18-6.39H0c0,7.68,5.52,15.89,19.96,15.89,11.61,0,20.16-5.12,20.16-14.64,0-10.05-7.37-12.94-17.24-15.3Z\"\/>\n      <path class=\"cls-1\" d=\"M218.58,48.47L191.27,1.19l-27.29,47.28h54.6ZM202.39,38.74h-22.23l11.11-19.25,11.12,19.25Z\"\/>\n      <polygon class=\"cls-1\" points=\"191.28 77.13 202.39 57.88 180.16 57.88 191.28 77.13\"\/>\n      <path class=\"cls-1\" d=\"M46.63,65.43c-2.34-.41-4.13-.94-4.13-2.27,0-.97.61-1.89,3.04-1.89,2.19,0,2.97,1.07,2.97,2.22h4.52c0-3.72-2.54-6.11-7.07-6.11-5.51,0-7.96,2.36-7.96,6.24s4.22,4.62,6.39,5.17c2.94.82,4.73,1.02,4.73,2.88,0,1.31-.99,2.12-3.59,2.12-2.37,0-3.75-1.04-3.75-2.61h-4.49c0,3.14,2.26,6.49,8.15,6.49,4.74,0,8.24-2.09,8.24-5.98,0-4.11-3.01-5.28-7.05-6.25Z\"\/>\n      <polygon class=\"cls-1\" points=\"63.62 69.55 71.44 69.55 71.44 65.68 63.62 65.68 63.62 61.73 72.73 61.73 72.73 57.86 59.12 57.86 59.12 77.18 72.86 77.18 72.86 73.31 63.62 73.31 63.62 69.55\"\/>\n      <polygon class=\"cls-1\" points=\"82.98 57.86 78.48 57.86 78.48 77.18 91.08 77.18 91.08 73.31 82.98 73.31 82.98 57.86\"\/>\n      <polygon class=\"cls-1\" points=\"95.65 77.18 100.16 77.18 100.16 70.24 107.97 70.24 107.97 66.38 100.16 66.38 100.16 61.73 109.26 61.73 109.26 57.86 95.65 57.86 95.65 77.18\"\/>\n      <path class=\"cls-1\" d=\"M131.16,65.43c-2.34-.41-4.13-.94-4.13-2.27,0-.97.61-1.89,3.04-1.89,2.19,0,2.97,1.07,2.97,2.22h4.52c0-3.72-2.54-6.11-7.07-6.11-5.51,0-7.96,2.36-7.96,6.24s4.22,4.62,6.39,5.17c2.94.82,4.73,1.02,4.73,2.88,0,1.31-.99,2.12-3.59,2.12-2.37,0-3.75-1.04-3.75-2.61h-4.49c0,3.14,2.26,6.49,8.15,6.49,4.74,0,8.24-2.09,8.24-5.98,0-4.11-3.01-5.28-7.05-6.25Z\"\/>\n      <polygon class=\"cls-1\" points=\"148.15 69.55 155.96 69.55 155.96 65.68 148.15 65.68 148.15 61.73 157.25 61.73 157.25 57.86 143.64 57.86 143.64 77.18 157.38 77.18 157.38 73.31 148.15 73.31 148.15 69.55\"\/>\n      <path class=\"cls-1\" d=\"M178.44,64.39c0-3.89-2.91-6.54-6.97-6.54h-8.47v19.32h4.5v-6.29h2.87l3.37,6.29h5.17l-4.08-6.96c2.22-1.01,3.61-3.08,3.61-5.82ZM171.28,67.02h-3.78v-5.3h3.78c1.48,0,2.66,1.12,2.66,2.67s-1.18,2.63-2.66,2.63Z\"\/>\n      <polygon class=\"cls-1\" points=\"210.21 69.55 218.03 69.55 218.03 65.68 210.21 65.68 210.21 61.73 219.32 61.73 219.32 57.86 205.71 57.86 205.71 77.18 219.45 77.18 219.45 73.31 210.21 73.31 210.21 69.55\"\/>\n      <polygon class=\"cls-1\" points=\"0 77.18 16.4 77.18 21.82 67.73 0 67.73 0 77.18\"\/>\n    <\/g>\n  <\/g>\n<\/svg><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e657e50 e-flex e-con-boxed e-con e-child\" data-id=\"e657e50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e846126 elementor-widget elementor-widget-shortcode\" data-id=\"e846126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><span data-tooltip=\"Adventure product\" class=\"redl_stimgs_tooltip redl_stimgs_hover-grow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><path d=\"M17.987 14.2426C18.5572 14.2426 19.0497 14.7091 19.0497 15.3052V34.9251C19.0497 35.4953 18.5832 35.9878 17.987 35.9878C17.3909 35.9878 16.9244 35.5212 16.9244 34.9251V15.3052C16.9244 14.7091 17.3909 14.2426 17.987 14.2426ZM28.2505 21.4737C27.8359 21.059 27.162 21.059 26.7732 21.4737C26.5659 21.6811 21.6933 26.6314 21.6933 34.9251C21.6933 35.4953 22.1598 35.9878 22.7559 35.9878C23.3521 35.9878 23.8186 35.5212 23.8186 34.9251C23.8186 33.4737 24 32.1519 24.2592 30.9597C24.6998 28.964 25.3996 27.3571 26.0475 26.1908C26.0475 26.1908 26.0734 26.1389 26.0993 26.113C27.1879 24.1173 28.2765 23.0029 28.3024 22.977C28.7171 22.5623 28.7171 21.8884 28.3024 21.4996M7.72354 21.4737C7.30886 21.8884 7.30886 22.5623 7.72354 22.977C7.72354 22.977 8.83801 24.0914 9.92657 26.0871C9.92657 26.0871 9.95248 26.1389 9.9784 26.1649C10.6004 27.3312 11.3261 28.964 11.7667 30.9338C12.0259 32.126 12.2073 33.4737 12.2073 34.8992C12.2073 35.4953 12.6739 35.9618 13.27 35.9618C13.8661 35.9618 14.3326 35.4953 14.3326 34.8992C14.3326 26.6314 9.46004 21.6811 9.2527 21.4737C8.83801 21.059 8.16415 21.059 7.74946 21.4737M22.1598 20.1001C22.1598 20.6703 22.6523 21.1627 23.2225 21.1627C23.7927 21.1627 24.2592 20.6703 24.2851 20.1001C24.2851 19.5299 23.7927 19.0374 23.2225 19.0374C22.6523 19.0374 22.1857 19.5299 22.1598 20.1001ZM12.7516 19.0633C12.1555 19.0633 11.7149 19.5558 11.689 20.126C11.689 20.6962 12.1814 21.1886 12.7516 21.1886C13.3218 21.1886 13.7883 20.6962 13.8143 20.126C13.8143 19.5558 13.3218 19.0633 12.7516 19.0633ZM27.4989 15.2016C27.4989 14.6314 27.0065 14.1389 26.4363 14.1389C25.8661 14.1389 25.3996 14.6314 25.3736 15.2016C25.3736 15.7718 25.8661 16.2642 26.4363 16.2642C27.0065 16.2642 27.473 15.7718 27.4989 15.2016ZM9.51188 16.2383C10.108 16.2383 10.5486 15.7459 10.5745 15.1757C10.5745 14.6055 10.0821 14.113 9.51188 14.113C8.94168 14.113 8.47516 14.6055 8.44924 15.1757C8.44924 15.7459 8.94168 16.2383 9.51188 16.2383ZM28.5616 28.8862C27.9654 28.8862 27.5248 29.3787 27.4989 29.9489C27.4989 30.5191 27.9914 31.0115 28.5616 31.0115C29.1318 31.0115 29.5983 30.5191 29.6242 29.9489C29.6501 29.3787 29.1318 28.8862 28.5616 28.8862ZM7.41253 28.8862C6.81641 28.8862 6.37581 29.3787 6.34989 29.9489C6.34989 30.5191 6.84233 31.0115 7.41253 31.0115C7.98272 31.0115 8.44924 30.5191 8.47516 29.9489C8.47516 29.3787 7.98272 28.8862 7.41253 28.8862ZM32.7862 25.4132C32.1901 25.4132 31.7495 25.9057 31.7235 26.4759C31.7235 27.0461 32.216 27.5385 32.7862 27.5385C33.3564 27.5385 33.8229 27.0461 33.8488 26.4759C33.8747 25.9057 33.3564 25.4132 32.7862 25.4132ZM3.16199 25.4132C2.56587 25.4132 2.12527 25.9057 2.09935 26.4759C2.09935 27.0461 2.59179 27.5385 3.16199 27.5385C3.73218 27.5385 4.1987 27.0461 4.22462 26.4759C4.25054 25.9057 3.73218 25.4132 3.16199 25.4132ZM31.8272 16.9381C31.257 16.9381 30.7646 17.4046 30.7646 18.0007C30.7646 18.5968 31.2311 19.0633 31.8272 19.0633H32.3197V19.5558C32.3197 20.126 32.7862 20.6184 33.3823 20.6184C33.9784 20.6184 34.4449 20.1519 34.4449 19.5558V19.0633H34.9374C35.5076 19.0633 36 18.5968 36 18.0007C36 17.4046 35.5335 16.9381 34.9374 16.9381H34.4449V16.4456C34.4449 15.8495 33.9784 15.383 33.3823 15.383C32.7862 15.383 32.3197 15.8495 32.3197 16.4456V16.9381H31.8272ZM1.06263 16.9381C0.492441 16.9381 0 17.4046 0 18.0007C0 18.5968 0.466523 19.0633 1.06263 19.0633H1.55508V19.5558C1.55508 20.126 2.0216 20.6184 2.61771 20.6184C3.21382 20.6184 3.68035 20.1519 3.68035 19.5558V19.0633H4.17279C4.74298 19.0633 5.23542 18.5968 5.23542 18.0007C5.23542 17.4046 4.7689 16.9381 4.17279 16.9381H3.68035V16.4456C3.68035 15.8495 3.21382 15.383 2.61771 15.383C2.0216 15.383 1.55508 15.8495 1.55508 16.4456V16.9381H1.06263ZM29.6242 10.5882H30.1166C30.7127 10.5882 31.1793 10.1217 31.1793 9.52555C31.1793 8.92944 30.7127 8.46291 30.1166 8.46291H29.6242V7.97047C29.6242 7.40028 29.1577 6.90784 28.5616 6.90784C27.9654 6.90784 27.4989 7.37436 27.4989 7.97047V8.46291H27.0065C26.4363 8.46291 25.9438 8.92944 25.9438 9.52555C25.9438 10.1217 26.4104 10.5882 27.0065 10.5882H27.4989V11.0806C27.4989 11.6508 27.9654 12.1433 28.5616 12.1433C29.1577 12.1433 29.6242 11.6767 29.6242 11.0806V10.5882ZM4.82073 9.52555C4.82073 10.0957 5.28726 10.5882 5.88337 10.5882H6.37581V11.0806C6.37581 11.6508 6.84233 12.1433 7.43844 12.1433C8.03456 12.1433 8.50108 11.6767 8.50108 11.0806V10.5882H8.99352C9.56371 10.5882 10.0562 10.1217 10.0562 9.52555C10.0562 8.92944 9.58963 8.46291 8.99352 8.46291H8.50108V7.97047C8.50108 7.40028 8.03456 6.90784 7.43844 6.90784C6.84233 6.90784 6.37581 7.37436 6.37581 7.97047V8.46291H5.88337C5.28726 8.46291 4.82073 8.92944 4.82073 9.52555ZM13.8402 10.5363C13.8402 10.8992 13.9698 11.2361 14.2808 11.4435C14.4622 11.5731 14.6695 11.6508 14.9028 11.6508C15.0324 11.6508 15.162 11.6508 15.2916 11.5731L18.013 10.5104L20.7343 11.5731C21.0713 11.7027 21.4341 11.6508 21.7451 11.4435C22.0302 11.2361 22.2117 10.8992 22.1857 10.5363L22.0043 7.63354L23.8445 5.37868C24.0778 5.09358 24.1555 4.73073 24.0259 4.3938C23.9222 4.05687 23.6371 3.79769 23.3002 3.69402L20.4752 2.96832L18.8942 0.506112C18.6868 0.195097 18.3758 0.0136719 18.013 0.0136719C17.6501 0.0136719 17.3132 0.195097 17.1318 0.506112L15.5508 2.96832L12.7257 3.69402C12.3888 3.79769 12.1037 4.05687 12 4.3938C11.8963 4.73073 11.9482 5.1195 12.1814 5.37868L14.0216 7.63354L13.8402 10.5363Z\" fill=\"#809EAD\"><\/path><\/svg><\/span><span data-tooltip=\"Self-Serve Option\" class=\"redl_stimgs_tooltip redl_stimgs_hover-grow\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><path d=\"M18.3668 18.1771C18.8182 18.1771 19.1003 18.5721 19.1003 18.9671C19.1003 19.362 18.8182 19.757 18.3668 19.757H17.4075V18.1771H18.3668ZM31.8244 6.52505C32.1066 6.38399 32.3041 5.989 32.3041 5.56581C32.3041 5.14261 32.1066 4.74762 31.8244 4.60656C31.5987 4.49371 31.4295 4.46549 31.0063 4.46549H27.5643C27.2539 4.46549 26.8307 4.46549 26.5486 4.80405C26.2382 5.14261 26.2382 5.59402 26.2382 5.96079V12.8166C26.2382 13.3809 26.2382 13.5783 26.3793 13.8605C26.5486 14.199 26.8871 14.453 27.3386 14.453C27.79 14.453 28.1285 14.199 28.2978 13.8605C28.4389 13.5783 28.4389 13.3809 28.4389 12.8166V10.5595H30.4702C30.9216 10.5595 31.0909 10.5595 31.2884 10.4185C31.5705 10.2774 31.768 9.88242 31.768 9.45922C31.768 9.03603 31.5705 8.64104 31.2884 8.49998C31.0627 8.38712 30.8934 8.35891 30.4702 8.35891H28.4389V6.60969H31.0063C31.4577 6.60969 31.627 6.60969 31.8244 6.46863M29.2571 19.4749V18.1771H31.2602C31.5987 18.1771 31.7398 18.1771 31.9091 18.0642C32.1066 17.9514 32.2759 17.6693 32.2759 17.3307C32.2759 16.9921 32.1066 16.71 31.9091 16.5972C31.7398 16.5125 31.627 16.4843 31.2602 16.4843H28.5799C28.326 16.4843 28.0157 16.4843 27.79 16.7382C27.5643 16.9921 27.5643 17.3589 27.5643 17.641V23.058C27.5643 23.3401 27.5643 23.7069 27.79 23.9608C28.0157 24.2429 28.326 24.2429 28.5799 24.2429H31.2602C31.5987 24.2429 31.7398 24.2429 31.9091 24.1301C32.1066 24.0172 32.2759 23.7351 32.2759 23.3965C32.2759 23.058 32.1066 22.7758 31.9091 22.663C31.7398 22.5783 31.627 22.5501 31.2602 22.5501H29.2571V21.1959H30.837C31.1755 21.1959 31.3166 21.1959 31.4859 21.083C31.6834 20.9702 31.8527 20.6881 31.8527 20.3495C31.8527 20.0109 31.6834 19.7288 31.4859 19.616C31.3166 19.5313 31.1755 19.5031 30.837 19.5031H29.2571V19.4749ZM26.5768 17.9232C26.6897 17.5282 26.7179 17.3871 26.6897 17.1614C26.6332 16.6536 26.1536 16.4279 25.8715 16.4279C25.674 16.4279 25.5047 16.5125 25.3636 16.6536C25.2226 16.8229 25.1661 16.9639 25.0533 17.3589L24.0376 20.9138L23.0219 17.3589C22.9091 16.9639 22.8527 16.8229 22.7116 16.6536C22.5987 16.5125 22.4013 16.4279 22.2038 16.4279C21.9216 16.4279 21.442 16.6254 21.3856 17.1614C21.3856 17.3871 21.3856 17.5282 21.4984 17.9232L23.1066 23.3683C23.2194 23.7633 23.3041 23.9326 23.4451 24.0454C23.5862 24.2147 23.7837 24.2711 24.0094 24.2711C24.2351 24.2711 24.4326 24.2147 24.5737 24.0454C24.7147 23.9044 24.7994 23.7633 24.9122 23.3683L26.5204 17.9232M19.6646 20.9984C20.3699 20.5752 20.7649 19.8135 20.7649 18.9953C20.7649 17.7257 19.9467 16.5125 18.4232 16.5125H16.7304C16.4765 16.5125 16.1661 16.5125 15.9404 16.7664C15.7147 17.0204 15.7147 17.3871 15.7147 17.6693V23.0015C15.7147 23.4247 15.7147 23.594 15.8276 23.8197C15.9404 24.1019 16.2226 24.2993 16.5611 24.2993C16.8997 24.2993 17.1818 24.1019 17.2947 23.8197C17.4075 23.594 17.4075 23.4247 17.4075 23.0015V21.3652H17.9718L19.0721 23.5376C19.2696 23.9326 19.4671 24.2993 19.8903 24.2993C20.0313 24.2993 20.1724 24.2429 20.3135 24.1583C20.5956 23.989 20.7367 23.7351 20.7367 23.3965C20.7367 23.1426 20.6803 23.0015 20.4828 22.6066L19.6646 20.9984ZM11.5674 19.4749V18.1771H13.5705C13.9091 18.1771 14.0502 18.1771 14.2194 18.0642C14.4451 17.9514 14.5862 17.6693 14.5862 17.3307C14.5862 16.9921 14.4451 16.71 14.2194 16.5972C14.0502 16.5125 13.9091 16.4843 13.5705 16.4843H10.8903C10.6364 16.4843 10.326 16.4843 10.1003 16.7382C9.87461 16.9921 9.87461 17.3589 9.87461 17.641V23.058C9.87461 23.3401 9.87461 23.7069 10.1003 23.9608C10.326 24.2429 10.6364 24.2429 10.8903 24.2429H13.5705C13.9091 24.2429 14.0502 24.2429 14.2194 24.1301C14.4451 24.0172 14.5862 23.7351 14.5862 23.3965C14.5862 23.058 14.4451 22.7758 14.2194 22.663C14.0502 22.5783 13.9091 22.5501 13.5705 22.5501H11.5674V21.1959H13.1473C13.4859 21.1959 13.627 21.1959 13.7962 21.083C13.9937 20.9702 14.163 20.6881 14.163 20.3495C14.163 20.0109 13.9937 19.7288 13.7962 19.616C13.627 19.5313 13.4859 19.5031 13.1473 19.5031H11.5674V19.4749ZM6.8558 14.5094C8.71787 14.5094 10.2414 13.4091 10.2414 11.3777C10.2414 10.4467 10.0439 9.71314 9.59248 9.20531C9.22571 8.78211 8.66144 8.49998 7.87147 8.38712L6.79937 8.21784C6.48903 8.16142 6.29154 8.04856 6.2069 7.93571C6.06583 7.76643 6.03762 7.59715 6.03762 7.39966C6.03762 7.03289 6.34796 6.55327 7.10972 6.55327C7.5047 6.55327 7.9279 6.63791 8.32288 6.8354C8.54859 6.94825 8.83072 7.08932 9.08464 7.08932C9.36677 7.08932 9.56426 6.94825 9.70533 6.75076C9.87461 6.52505 9.95925 6.24292 9.95925 5.989C9.95925 5.45295 9.59248 5.02976 9.05643 4.77584C8.52038 4.55013 7.9279 4.40907 7.16614 4.40907C5.16301 4.40907 3.94984 5.73509 3.94984 7.56894C3.94984 8.41534 4.14734 9.09245 4.54232 9.57208C4.9373 10.0235 5.52978 10.3338 6.31975 10.4467L7.39185 10.616C7.67398 10.6724 7.87147 10.757 7.95611 10.8981C8.06896 11.0392 8.12539 11.2367 8.12539 11.4906C8.12539 12.0548 7.73041 12.3934 6.8558 12.3934C6.31975 12.3934 5.84013 12.2523 5.41693 12.0266C4.99373 11.8291 4.79624 11.7445 4.57053 11.7445C4.34483 11.7445 4.14734 11.8009 3.97806 11.9984C3.78056 12.1959 3.69592 12.5345 3.69592 12.7884C3.69592 13.5219 4.11912 13.8887 4.85266 14.2272C5.44514 14.5094 6.12226 14.5658 6.8558 14.5658M6.15047 24.2993C7.58934 24.2993 8.80251 23.4247 8.80251 21.873C8.80251 21.1395 8.66144 20.5752 8.29467 20.1802C8.01254 19.8417 7.56113 19.6442 6.94044 19.5313L6.12226 19.3903C5.86834 19.362 5.72727 19.2492 5.64263 19.1646C5.52978 19.0517 5.50157 18.9106 5.50157 18.7414C5.50157 18.4592 5.75549 18.0925 6.31975 18.0925C6.63009 18.0925 6.96865 18.1771 7.25078 18.3182C7.42006 18.4028 7.64577 18.5156 7.84326 18.5156C8.04075 18.5156 8.23824 18.4028 8.32288 18.2617C8.46395 18.0925 8.52038 17.8667 8.52038 17.6693C8.52038 17.2461 8.23824 16.9357 7.81505 16.7382C7.39185 16.5407 6.94044 16.4561 6.34796 16.4561C4.79624 16.4561 3.83699 17.5 3.83699 18.9106C3.83699 19.5877 4.00627 20.0956 4.31661 20.4624C4.62696 20.8291 5.07837 21.0548 5.69906 21.1395L6.51724 21.2805C6.74295 21.3088 6.88401 21.3934 6.96865 21.478C7.05329 21.5909 7.10972 21.7602 7.10972 21.9294C7.10972 22.3809 6.79937 22.6348 6.12226 22.6348C5.69906 22.6348 5.33229 22.5219 4.99373 22.3526C4.65517 22.1834 4.51411 22.1269 4.34483 22.1269C4.17555 22.1269 4.00627 22.1834 3.89342 22.3244C3.75235 22.4937 3.66771 22.7476 3.66771 22.9451C3.66771 23.5094 4.00627 23.8197 4.57053 24.0454C5.02194 24.2429 5.55799 24.2993 6.12226 24.2993M11.652 12.9294C11.652 13.2962 11.652 13.7476 11.9624 14.0862C12.2727 14.4247 12.6677 14.4247 12.9781 14.4247H16.4201C16.8715 14.4247 17.0408 14.4247 17.2382 14.2837C17.5204 14.1426 17.7179 13.7476 17.7179 13.3244C17.7179 12.9012 17.5204 12.5062 17.2382 12.3652C17.0125 12.2523 16.8715 12.2241 16.4201 12.2241H13.8527V10.4749H15.884C16.3354 10.4749 16.5047 10.4749 16.7022 10.3338C16.9843 10.1928 17.1818 9.79778 17.1818 9.37458C17.1818 8.95139 16.9843 8.5564 16.7022 8.41534C16.4765 8.30248 16.3354 8.27427 15.884 8.27427H13.8527V6.60969H16.4201C16.8715 6.60969 17.0408 6.60969 17.2382 6.46863C17.5204 6.32756 17.7179 5.93258 17.7179 5.50938C17.7179 5.08618 17.5204 4.6912 17.2382 4.55013C17.0125 4.43728 16.8715 4.40907 16.4201 4.40907H12.9781C12.6677 4.40907 12.2445 4.40907 11.9624 4.74762C11.652 5.08618 11.652 5.53759 11.652 5.90436V12.9294ZM19.1567 12.9294C19.1567 13.2962 19.1567 13.7476 19.4671 14.0862C19.7774 14.4247 20.1724 14.4247 20.4828 14.4247H23.7837C24.2069 14.4247 24.3762 14.4247 24.6019 14.2837C24.884 14.1426 25.0815 13.7476 25.0815 13.3244C25.0815 12.9012 24.884 12.5062 24.6019 12.3652C24.3762 12.2523 24.2069 12.2241 23.7837 12.2241H21.3292V6.04543C21.3292 5.48117 21.3292 5.28367 21.1881 5.00154C21.047 4.66298 20.6803 4.40907 20.2288 4.40907C19.7774 4.40907 19.4389 4.66298 19.2696 5.00154C19.1285 5.28367 19.1285 5.48117 19.1285 6.04543V12.9012H19.1567V12.9294ZM32.1348 0.0078125C34.279 0.0078125 36 1.72882 36 3.87302V24.9483C36 27.0925 34.279 28.8135 32.1348 28.8135H28.8903V34.9357C28.8903 35.895 27.7335 36.3464 27.0846 35.6693L20.3699 28.8135H3.8652C1.721 28.8135 0 27.0925 0 24.9483V3.87302C0 1.72882 1.721 0.0078125 3.8652 0.0078125H32.1348Z\" fill=\"#809EAD\"><\/path><\/svg><\/span><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ada408 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8ada408\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:&quot;800&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SILEXA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-557f1e2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"557f1e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PourMyBev<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b6b8d6 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"0b6b8d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;600&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ed94a1 elementor-invisible elementor-widget elementor-widget-jet-listing-grid\" data-id=\"9ed94a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;auto&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;400&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-auto grid-col-tablet-auto grid-col-mobile-auto jet-listing-grid--9077\" data-queried-id=\"24699|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:9077,&quot;posts_num&quot;:100,&quot;columns&quot;:&quot;auto&quot;,&quot;columns_tablet&quot;:&quot;auto&quot;,&quot;columns_mobile&quot;:&quot;auto&quot;,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;No data was found&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:&quot;yes&quot;,&quot;custom_query_id&quot;:&quot;4&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"query\" data-listing-id=\"9077\" data-query-id=\"4\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-128\" data-post-id=\"128\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9077\" class=\"elementor elementor-9077\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-34a2266 e-con-full e-transform e-flex e-con e-parent\" data-id=\"34a2266\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/redl.net\/en\/branche\/restaurant-cafe-en\/\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4d29e57 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Restaurant &amp;amp; Cafe&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"4d29e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4d29e57\" class=\"jet-tooltip-widget__content\">Restaurant &amp; Cafe<\/div>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/restaurant.svg\" class=\"attachment-large size-large wp-image-18640\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-124\" data-post-id=\"124\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9077\" class=\"elementor elementor-9077\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-34a2266 e-con-full e-transform e-flex e-con e-parent\" data-id=\"34a2266\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/redl.net\/en\/branche\/hotel-spa-resort-en\/\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4d29e57 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Hotel, Spa &amp;amp; Resort&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"4d29e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4d29e57\" class=\"jet-tooltip-widget__content\">Hotel, Spa &amp; Resort<\/div>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/hotel.svg\" class=\"attachment-large size-large wp-image-18642\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-126\" data-post-id=\"126\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9077\" class=\"elementor elementor-9077\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-34a2266 e-con-full e-transform e-flex e-con e-parent\" data-id=\"34a2266\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/redl.net\/en\/branche\/kreuzfahrtschiff-en\/\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4d29e57 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Cruise Ship&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"4d29e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4d29e57\" class=\"jet-tooltip-widget__content\">Cruise Ship<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/cruiseship.svg\" class=\"attachment-large size-large wp-image-18646\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-129\" data-post-id=\"129\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9077\" class=\"elementor elementor-9077\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-34a2266 e-con-full e-transform e-flex e-con e-parent\" data-id=\"34a2266\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/redl.net\/en\/branche\/stadion-event-en\/\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4d29e57 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Stadium &amp;amp; Event&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"4d29e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4d29e57\" class=\"jet-tooltip-widget__content\">Stadium &amp; Event<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/stadium.svg\" class=\"attachment-large size-large wp-image-18645\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-122\" data-post-id=\"122\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9077\" class=\"elementor elementor-9077\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-34a2266 e-con-full e-transform e-flex e-con e-parent\" data-id=\"34a2266\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/redl.net\/en\/branche\/bar-club-apres-ski-en\/\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4d29e57 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Bar, Club &amp;amp; Apr\\u00e8s-Ski&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"4d29e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4d29e57\" class=\"jet-tooltip-widget__content\">Bar, Club &amp; Apr\u00e8s-Ski<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/disco.svg\" class=\"attachment-large size-large wp-image-18641\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-125\" data-post-id=\"125\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9077\" class=\"elementor elementor-9077\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<a class=\"elementor-element elementor-element-34a2266 e-con-full e-transform e-flex e-con e-parent\" data-id=\"34a2266\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/redl.net\/en\/branche\/office-cafeteria\/\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-4d29e57 elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Office &amp;amp; Cafeteria&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"4d29e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-4d29e57\" class=\"jet-tooltip-widget__content\">Office &amp; Cafeteria<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/corpcatering.svg\" class=\"attachment-large size-large wp-image-18648\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfeb48d elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"dfeb48d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:&quot;500&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>POURMYBEV FOR FAST-FOOD RESTAURANTS: FREE REFILL, BUT WITH CONTROL &#8211; TIME AND QUANTITY-BASED BEVERAGE MANAGEMENT WITH QR-CODE.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52fead5 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"52fead5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;800&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e090123 elementor-widget elementor-widget-heading\" data-id=\"e090123\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">best<br>suitable for:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dba8f0 elementor-widget elementor-widget-jet-listing-grid\" data-id=\"1dba8f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;auto&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-auto grid-col-tablet-auto grid-col-mobile-auto jet-listing-grid--8959\" data-queried-id=\"24699|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:8959,&quot;posts_num&quot;:100,&quot;columns&quot;:&quot;auto&quot;,&quot;columns_tablet&quot;:&quot;auto&quot;,&quot;columns_mobile&quot;:&quot;auto&quot;,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;No data was found&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:&quot;yes&quot;,&quot;custom_query_id&quot;:&quot;1&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:false,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"query\" data-listing-id=\"8959\" data-query-id=\"1\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-107\" data-post-id=\"107\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"8959\" class=\"elementor elementor-8959\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38435cb e-con-full e-transform e-flex e-con e-parent\" data-id=\"38435cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-8d398fc elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Beer&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"8d398fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-8d398fc\" class=\"jet-tooltip-widget__content\">Beer<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/beer.svg\" class=\"attachment-large size-large wp-image-18635\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-108\" data-post-id=\"108\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"8959\" class=\"elementor elementor-8959\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38435cb e-con-full e-transform e-flex e-con e-parent\" data-id=\"38435cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-8d398fc elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Hot drinks&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"8d398fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-8d398fc\" class=\"jet-tooltip-widget__content\">Hot drinks<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/hotbevs.svg\" class=\"attachment-large size-large wp-image-18632\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-110\" data-post-id=\"110\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"8959\" class=\"elementor elementor-8959\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38435cb e-con-full e-transform e-flex e-con e-parent\" data-id=\"38435cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-8d398fc elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Juice \\\/ Water&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"8d398fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-8d398fc\" class=\"jet-tooltip-widget__content\">Juice \/ Water<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/juice.svg\" class=\"attachment-large size-large wp-image-18634\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-111\" data-post-id=\"111\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"8959\" class=\"elementor elementor-8959\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38435cb e-con-full e-transform e-flex e-con e-parent\" data-id=\"38435cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-8d398fc elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Snacks&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"8d398fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-8d398fc\" class=\"jet-tooltip-widget__content\">Snacks<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/snacks.svg\" class=\"attachment-large size-large wp-image-18636\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-112\" data-post-id=\"112\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"8959\" class=\"elementor elementor-8959\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38435cb e-con-full e-transform e-flex e-con e-parent\" data-id=\"38435cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-8d398fc elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Spirits&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"8d398fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-8d398fc\" class=\"jet-tooltip-widget__content\">Spirits<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/spirits.svg\" class=\"attachment-large size-large wp-image-18637\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-113\" data-post-id=\"113\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"8959\" class=\"elementor elementor-8959\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38435cb e-con-full e-transform e-flex e-con e-parent\" data-id=\"38435cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-8d398fc elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Wine \\\/ Sparkling wine&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"8d398fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-8d398fc\" class=\"jet-tooltip-widget__content\">Wine \/ Sparkling wine<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/wine.svg\" class=\"attachment-large size-large wp-image-18638\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-114\" data-post-id=\"114\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"8959\" class=\"elementor elementor-8959\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38435cb e-con-full e-transform e-flex e-con e-parent\" data-id=\"38435cb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.1,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"jet-tooltip-widget elementor-element elementor-element-8d398fc elementor-widget elementor-widget-image\" role=\"tooltip\" data-jet-tricks-settings=\"{&quot;tooltip&quot;:&quot;true&quot;,&quot;tooltipDescription&quot;:&quot;Bottles&quot;,&quot;tooltipPlacement&quot;:&quot;top&quot;,&quot;tooltipArrow&quot;:true,&quot;xOffset&quot;:0,&quot;yOffset&quot;:5,&quot;tooltipAnimation&quot;:&quot;fade&quot;,&quot;tooltipTrigger&quot;:&quot;mouseenter&quot;,&quot;zIndex&quot;:999,&quot;appendTo&quot;:&quot;widget&quot;,&quot;customSelector&quot;:&quot;&quot;,&quot;delay&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;followCursor&quot;:&quot;false&quot;}\" data-id=\"8d398fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"jet-tricks-tooltip-content-8d398fc\" class=\"jet-tooltip-widget__content\">Bottles<\/div>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"22\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/bottles_1.svg\" class=\"attachment-large size-large wp-image-18639\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e27c8ae elementor-hidden-mobile e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"e27c8ae\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;1200&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-301712d e-con-full e-flex e-con e-child\" data-id=\"301712d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3370d4e elementor-widget elementor-widget-heading\" data-id=\"3370d4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SMART FREE REFILL: QR CODE - TOTAL CONTROL!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eecf689 elementor-widget elementor-widget-text-editor\" data-id=\"eecf689\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With PourMyBev, fast food restaurants retain full control over free refill offers. At checkout, the guest receives a QR code that gives them access to the drinks station for a limited time and quantity. After that, the system locks automatically to prevent unauthorized withdrawals.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30c9a73 e-flex e-con-boxed elementor-invisible e-con e-child\" data-id=\"30c9a73\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;200&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-da88b62 e-flex e-con-boxed e-con e-child\" data-id=\"da88b62\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c464938 e-transform elementor-invisible elementor-widget elementor-widget-button\" data-id=\"c464938\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1.01&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:&quot;400&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-touchscreen\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">4.3\" TOUCHSCREEN, QR CODE READER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbcf90c e-transform elementor-invisible elementor-widget elementor-widget-button\" data-id=\"bbcf90c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1.01&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:&quot;600&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-settings\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">NUMBER OF SERVINGS AND VALIDITY DURATION ADJUSTABLE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-667264a e-transform elementor-invisible elementor-widget elementor-widget-button\" data-id=\"667264a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1.01&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:&quot;800&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-together\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">COMPATIBLE WITH MANY POST-MIX DISPENSING SYSTEMS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e04b065 e-transform elementor-invisible elementor-widget elementor-widget-button\" data-id=\"e04b065\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1.01&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:&quot;1000&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-expand\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VARIOUS DESIGN AND HOUSING OPTIONS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-603eb77 e-transform elementor-invisible elementor-widget elementor-widget-button\" data-id=\"603eb77\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;1.01&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInLeft&quot;,&quot;_animation_delay&quot;:&quot;1200&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-dashboard\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EASY MANAGEMENT VIA WEB BROWSER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6de7338 e-flex e-con-boxed e-con e-child\" data-id=\"6de7338\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f4f98a elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"3f4f98a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HIGH<br>LIGHTS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0eccdb6 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"0eccdb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">HIGHLIGHTS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0becb3d e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"0becb3d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:&quot;200&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-26ee49e e-con-full e-flex e-con e-child\" data-id=\"26ee49e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ce95ff elementor-widget elementor-widget-heading\" data-id=\"0ce95ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">POUR IT YOURSELF, SAVE TIME, CREATE AN EXPERIENCE <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db34c0f elementor-widget elementor-widget-text-editor\" data-id=\"db34c0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With POURMYBEV, you can rely on a modern and efficient solution that revolutionizes beverage service. Your guests order and pay by QR code or room card and pour their drink themselves &#8211; quickly, easily and contactlessly. Whether in hotels, self-service restaurants or event locations: POURMYBEV increases the satisfaction of your guests, reduces waiting times and saves valuable staff resources.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfea3fa e-con-full e-flex e-con e-child\" data-id=\"bfea3fa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44faf57 elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"44faf57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/PourMyBev-Station-cc-1.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64fbaa4 e-flex e-con-boxed e-con e-parent\" data-id=\"64fbaa4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-26641295 e-con-full e-flex e-con e-child\" data-id=\"26641295\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-618748bc elementor-widget elementor-widget-heading\" data-id=\"618748bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why silexa?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11c2374d elementor-widget elementor-widget-heading\" data-id=\"11c2374d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recognize the difference. Experience the advantage.   <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8183f6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2d8183f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24636b42 e-con-full e-flex e-con e-child\" data-id=\"24636b42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16807d02 elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"16807d02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;2ef14ae&quot;},{&quot;slide_title&quot;:&quot;Slide #2&quot;,&quot;_id&quot;:&quot;f6584c1&quot;},{&quot;slide_title&quot;:&quot;Slide #3&quot;,&quot;_id&quot;:&quot;ac8bba2&quot;}],&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:&quot;4000&quot;,&quot;offset_sides&quot;:&quot;right&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;60&quot;,&quot;sizes&quot;:[]},&quot;offset_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;100&quot;,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;offset_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-624c96d0 e-flex e-con-boxed e-con e-child\" data-id=\"624c96d0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30aa107f elementor-widget elementor-widget-image\" data-id=\"30aa107f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/Design-ohne-Titel-27-1024x1024.png\" class=\"attachment-large size-large wp-image-18903\" alt=\"TiPOS ZAGU, analysis image Canva\" srcset=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/Design-ohne-Titel-27-1024x1024.png 1024w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/Design-ohne-Titel-27-300x300.png 300w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/Design-ohne-Titel-27-150x150.png 150w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/Design-ohne-Titel-27-768x768.png 768w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/Design-ohne-Titel-27.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e5ed4c6 e-con-full e-flex e-con e-child\" data-id=\"4e5ed4c6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f09e462 elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"6f09e462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chart-line\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ca15296 elementor-widget elementor-widget-text-editor\" data-id=\"3ca15296\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No excessive monthly fees, no revenue share &#8211; with us you simply buy your device and keep your margin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64f19eff e-flex e-con-boxed e-con e-child\" data-id=\"64f19eff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:&quot;400&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a6ccd61 elementor-widget elementor-widget-image\" data-id=\"6a6ccd61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourmyBev_Schauraum-771x1024.jpg\" class=\"attachment-large size-large wp-image-23246\" alt=\"PourmyBev_showroom\" srcset=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourmyBev_Schauraum-771x1024.jpg 771w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourmyBev_Schauraum-226x300.jpg 226w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourmyBev_Schauraum-768x1020.jpg 768w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourmyBev_Schauraum-1157x1536.jpg 1157w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourmyBev_Schauraum-1542x2048.jpg 1542w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourmyBev_Schauraum-scaled.jpg 1928w\" sizes=\"(max-width: 771px) 100vw, 771px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f8d71f0 e-con-full e-flex e-con e-child\" data-id=\"4f8d71f0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18dbac6 elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"18dbac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-selfserve\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61552a2c elementor-widget elementor-widget-text-editor\" data-id=\"61552a2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>There is no standard in self-service areas &#8211; but <em>we<\/em> deliver it. PourMyBev is tailored precisely to your requirements, but costs no more than a standard solution. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55cfc83b e-con-full e-flex e-con e-child\" data-id=\"55cfc83b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:&quot;200&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf3a92d elementor-widget elementor-widget-image\" data-id=\"5bf3a92d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia-1024x768.jpg\" class=\"attachment-large size-large wp-image-21436\" alt=\"PourMyBev Olympia Coca Cola\" srcset=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia-1024x768.jpg 1024w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia-300x225.jpg 300w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia-768x576.jpg 768w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia-1536x1152.jpg 1536w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia.jpg 2016w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5652c2f0 e-con-full e-flex e-con e-child\" data-id=\"5652c2f0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-340fdbcc elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"340fdbcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-silexanet\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cf9bac6 elementor-widget elementor-widget-text-editor\" data-id=\"6cf9bac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With PourMyBev, we combine dispensing systems, vending machines, coffee machines, locking systems and much more into a centrally controllable solution &#8211; for a seamless, secure and efficient self-service experience.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36631cf e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"36631cf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;200&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8a20534 e-con-full e-flex e-con e-child\" data-id=\"8a20534\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97b2567 elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"97b2567\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;19ac0a0&quot;},{&quot;slide_title&quot;:&quot;Slide #2&quot;,&quot;_id&quot;:&quot;af07909&quot;},{&quot;slide_title&quot;:&quot;Slide #3&quot;,&quot;_id&quot;:&quot;c3cd46e&quot;}],&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:&quot;4000&quot;,&quot;offset_sides&quot;:&quot;left&quot;,&quot;offset_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;100&quot;,&quot;sizes&quot;:[]},&quot;offset_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;100&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;20&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;20&quot;,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d253819 e-flex e-con-boxed e-con e-child\" data-id=\"d253819\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1244fca elementor-widget elementor-widget-image\" data-id=\"1244fca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"144\" height=\"250\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/PourMyBev-01.svg\" class=\"attachment-large size-large wp-image-21135\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-896ace9 e-flex e-con-boxed e-con e-child\" data-id=\"896ace9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd529e4 elementor-widget elementor-widget-image\" data-id=\"bd529e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"285\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/PourMyBev-02.svg\" class=\"attachment-large size-large wp-image-21137\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cb8901 e-flex e-con-boxed e-con e-child\" data-id=\"3cb8901\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b10d4e6 elementor-widget elementor-widget-image\" data-id=\"b10d4e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"125\" height=\"203\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/PourMyBev-03.svg\" class=\"attachment-large size-large wp-image-21139\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e72ceb e-flex e-con-boxed e-con e-child\" data-id=\"3e72ceb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-836dd4c elementor-widget elementor-widget-heading\" data-id=\"836dd4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TECHNICAL DATA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed8423f elementor-widget elementor-widget-text-editor\" data-id=\"ed8423f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>DIMENSIONS (MM)<\/strong> <br>160 W | 314 H | 180 D<\/p><p><strong>DISPLAY<\/strong><br>4,3\u201c color touchscreen<\/p><p><strong>REQUIREMENTS<\/strong><br>110-230VAC \/ 50-60Hz, LAN<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2834e8c e-con-full e-flex e-con e-child\" data-id=\"2834e8c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-030e99e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"030e99e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/06\/PourMyBev-EN.pdf\" download=\"download\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download product card<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81ae8b1 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"81ae8b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/Redl-UseCases-Collection.pdf\" download=\"Redl-Einsatzbereiche-Gesamt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download use cases<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4863ccf e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"4863ccf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;200&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1818a03 e-con-full e-flex e-con e-child\" data-id=\"1818a03\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e45ed8 elementor-widget elementor-widget-heading\" data-id=\"7e45ed8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">More than just drinks: SILEXA Coffee Terminal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-519899a elementor-widget elementor-widget-text-editor\" data-id=\"519899a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Offer your guests not only self-tapped drinks with <strong>PourMyBev<\/strong>, but also freshly brewed coffee at the touch of a button! The <strong>SILEXA Coffee Terminal<\/strong> perfectly complements your self-service offering and allows guests to provide themselves with high-quality coffee, cappuccino or espresso &#8211; quickly, easily and without waiting times. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-458ec16 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"458ec16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/redl.net\/en\/produkt\/coffee-terminal\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">learn more about this product<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29cc47b e-con-full e-flex e-con e-child\" data-id=\"29cc47b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3679 elementor-widget elementor-widget-image\" data-id=\"62f3679\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"726\" src=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/SILEXA-Coffee-Terminal-1024x929.jpg\" class=\"attachment-large size-large wp-image-18671\" alt=\"Silexa Coffee Terminal Coffee payment terminal\" srcset=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/SILEXA-Coffee-Terminal-1024x929.jpg 1024w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/SILEXA-Coffee-Terminal-300x272.jpg 300w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/SILEXA-Coffee-Terminal-768x697.jpg 768w, https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/SILEXA-Coffee-Terminal.jpg 1486w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e819fbf e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"e819fbf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:&quot;200&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d49c89a e-con-full e-flex e-con e-child\" data-id=\"d49c89a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e95ade4 elementor-widget elementor-widget-heading\" data-id=\"e95ade4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IMAGE GALLERY<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca674c elementor-widget elementor-widget-heading\" data-id=\"2ca674c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PourMyBev  in use<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25e32cb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"25e32cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5766e21 elementor-widget elementor-widget-gallery\" data-id=\"5766e21\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;12&quot;,&quot;sizes&quot;:[]},&quot;columns_mobile&quot;:&quot;2&quot;,&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;overlay_title&quot;:&quot;caption&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5766e21\" data-elementor-lightbox-title=\"Coca Cola, ES\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2NjUsInVybCI6Imh0dHBzOlwvXC9yZWRsLm5ldFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL1BvdXJNeUJldi5qcGciLCJzbGlkZXNob3ciOiI1NzY2ZTIxIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev-1024x929.jpg\" data-width=\"800\" data-height=\"726\" aria-label=\"PourMyBev Silexa Pour My Beverage\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCoca Cola, ES\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBeer-For-Events.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5766e21\" data-elementor-lightbox-title=\"Flower meadow, AT\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2NjMsInVybCI6Imh0dHBzOlwvXC9yZWRsLm5ldFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL1BvdXJNeUJlZXItRm9yLUV2ZW50cy5qcGciLCJzbGlkZXNob3ciOiI1NzY2ZTIxIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBeer-For-Events-1024x929.jpg\" data-width=\"800\" data-height=\"726\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tFlower meadow, AT\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5766e21\" data-elementor-lightbox-title=\"Coca Cola, FR\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjE0MzYsInVybCI6Imh0dHBzOlwvXC9yZWRsLm5ldFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDFcL0NvY2FDb2xhX09seW1waWEuanBnIiwic2xpZGVzaG93IjoiNTc2NmUyMSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/CocaCola_Olympia-1024x768.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"PourMyBev Olympia Coca Cola\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCoca Cola, FR\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/2019_ChiliEatsHoney.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5766e21\" data-elementor-lightbox-title=\"ChiliEatsHoney, AT\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM3MDUsInVybCI6Imh0dHBzOlwvXC9yZWRsLm5ldFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcLzIwMTlfQ2hpbGlFYXRzSG9uZXkuanBnIiwic2xpZGVzaG93IjoiNTc2NmUyMSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/2019_ChiliEatsHoney-1024x768.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"ChiliEatsHoney, Podersdorf, PourMyBev\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tChiliEatsHoney, AT\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/Huth_Rinderwahn_Redl_02.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5766e21\" data-elementor-lightbox-title=\"Rinderwahn, AT\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjM3MDcsInVybCI6Imh0dHBzOlwvXC9yZWRsLm5ldFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDRcL0h1dGhfUmluZGVyd2Fobl9SZWRsXzAyLmpwZyIsInNsaWRlc2hvdyI6IjU3NjZlMjEifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/04\/Huth_Rinderwahn_Redl_02.jpg\" data-width=\"800\" data-height=\"600\" aria-label=\"PourMyBev, Rinderwahn Wien\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRinderwahn, AT\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf3bbb8 e-flex e-con-boxed e-con e-parent\" data-id=\"cf3bbb8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Limited access to beverages via QR &#8211; prevents misuse, ideal for fast food chains &amp; smart beverage stations.<\/p>\n","protected":false},"featured_media":18665,"template":"","benefit":[105,106],"food-category":[107,108,110,111,112,113,114],"branche":[120],"use-case-bereich":[128,124,126,129,122,125],"class_list":["post-24699","produkt","type-produkt","status-publish","has-post-thumbnail","hentry","benefit-adventure-product","benefit-self-serve-option-en","food-category-beer","food-category-hot-drinks","food-category-juice-water","food-category-snacks-en","food-category-spirits","food-category-wine-sparkling-wine","food-category-bottles","branche-silexa-self-serve-en","use-case-bereich-restaurant-cafe-en","use-case-bereich-hotel-spa-resort-en","use-case-bereich-kreuzfahrtschiff-en","use-case-bereich-stadion-event-en","use-case-bereich-bar-club-apres-ski-en","use-case-bereich-office-cafeteria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PourMyBev - Free refill with control via QR code | Redl<\/title>\n<meta name=\"description\" content=\"Limited access to beverages via QR - prevents misuse, ideal for fast food chains &amp; smart beverage stations.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redl.net\/en\/produkt\/pourmybev\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PourMyBev - Free refill with control via QR code | Redl\" \/>\n<meta property=\"og:description\" content=\"Limited access to beverages via QR - prevents misuse, ideal for fast food chains &amp; smart beverage stations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redl.net\/en\/produkt\/pourmybev\/\" \/>\n<meta property=\"og:site_name\" content=\"Redl\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/redl.net\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T13:50:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1486\" \/>\n\t<meta property=\"og:image:height\" content=\"1348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/\",\"url\":\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/\",\"name\":\"PourMyBev - Free refill with control via QR code | Redl\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redl.net\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/PourMyBev.jpg\",\"datePublished\":\"2025-01-21T14:59:07+00:00\",\"dateModified\":\"2026-04-23T13:50:50+00:00\",\"description\":\"Limited access to beverages via QR - prevents misuse, ideal for fast food chains &amp; smart beverage stations.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redl.net\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/PourMyBev.jpg\",\"contentUrl\":\"https:\\\/\\\/redl.net\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/PourMyBev.jpg\",\"width\":1486,\"height\":1348,\"caption\":\"Coca Cola, ES\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/produkt\\\/pourmybev\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/redl.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/redl.net\\\/en\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PourMyBev\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/redl.net\\\/en\\\/\",\"name\":\"Redl\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redl.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/#organization\",\"name\":\"Redl\",\"url\":\"https:\\\/\\\/redl.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redl.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Redl-GmbH-Logo-SCREEN.svg\",\"contentUrl\":\"https:\\\/\\\/redl.net\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Redl-GmbH-Logo-SCREEN.svg\",\"width\":286.94,\"height\":70.87,\"caption\":\"Redl\"},\"image\":{\"@id\":\"https:\\\/\\\/redl.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/redl.net\\\/\",\"https:\\\/\\\/www.instagram.com\\\/redl_silexa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7B7UA6q6Pa_v2j5e5Hai2g\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/53409161\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PourMyBev - Free refill with control via QR code | Redl","description":"Limited access to beverages via QR - prevents misuse, ideal for fast food chains &amp; smart beverage stations.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redl.net\/en\/produkt\/pourmybev\/","og_locale":"en_US","og_type":"article","og_title":"PourMyBev - Free refill with control via QR code | Redl","og_description":"Limited access to beverages via QR - prevents misuse, ideal for fast food chains &amp; smart beverage stations.","og_url":"https:\/\/redl.net\/en\/produkt\/pourmybev\/","og_site_name":"Redl","article_publisher":"https:\/\/www.facebook.com\/redl.net\/","article_modified_time":"2026-04-23T13:50:50+00:00","og_image":[{"width":1486,"height":1348,"url":"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/redl.net\/en\/produkt\/pourmybev\/","url":"https:\/\/redl.net\/en\/produkt\/pourmybev\/","name":"PourMyBev - Free refill with control via QR code | Redl","isPartOf":{"@id":"https:\/\/redl.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redl.net\/en\/produkt\/pourmybev\/#primaryimage"},"image":{"@id":"https:\/\/redl.net\/en\/produkt\/pourmybev\/#primaryimage"},"thumbnailUrl":"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg","datePublished":"2025-01-21T14:59:07+00:00","dateModified":"2026-04-23T13:50:50+00:00","description":"Limited access to beverages via QR - prevents misuse, ideal for fast food chains &amp; smart beverage stations.","breadcrumb":{"@id":"https:\/\/redl.net\/en\/produkt\/pourmybev\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redl.net\/en\/produkt\/pourmybev\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/redl.net\/en\/produkt\/pourmybev\/#primaryimage","url":"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg","contentUrl":"https:\/\/redl.net\/wp-content\/uploads\/2025\/01\/PourMyBev.jpg","width":1486,"height":1348,"caption":"Coca Cola, ES"},{"@type":"BreadcrumbList","@id":"https:\/\/redl.net\/en\/produkt\/pourmybev\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/redl.net\/en\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/redl.net\/en\/produkte\/"},{"@type":"ListItem","position":3,"name":"PourMyBev"}]},{"@type":"WebSite","@id":"https:\/\/redl.net\/en\/#website","url":"https:\/\/redl.net\/en\/","name":"Redl","description":"","publisher":{"@id":"https:\/\/redl.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redl.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/redl.net\/en\/#organization","name":"Redl","url":"https:\/\/redl.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/redl.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/redl.net\/wp-content\/uploads\/2025\/02\/Redl-GmbH-Logo-SCREEN.svg","contentUrl":"https:\/\/redl.net\/wp-content\/uploads\/2025\/02\/Redl-GmbH-Logo-SCREEN.svg","width":286.94,"height":70.87,"caption":"Redl"},"image":{"@id":"https:\/\/redl.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/redl.net\/","https:\/\/www.instagram.com\/redl_silexa\/","https:\/\/www.youtube.com\/channel\/UC7B7UA6q6Pa_v2j5e5Hai2g","https:\/\/www.linkedin.com\/company\/53409161\/"]}]}},"_links":{"self":[{"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/produkt\/24699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/produkt"}],"about":[{"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/types\/produkt"}],"version-history":[{"count":21,"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/produkt\/24699\/revisions"}],"predecessor-version":[{"id":29946,"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/produkt\/24699\/revisions\/29946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/media\/18665"}],"wp:attachment":[{"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/media?parent=24699"}],"wp:term":[{"taxonomy":"benefit","embeddable":true,"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/benefit?post=24699"},{"taxonomy":"food-category","embeddable":true,"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/food-category?post=24699"},{"taxonomy":"branche","embeddable":true,"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/branche?post=24699"},{"taxonomy":"use-case-bereich","embeddable":true,"href":"https:\/\/redl.net\/en\/wp-json\/wp\/v2\/use-case-bereich?post=24699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}